{"id":408,"count":72,"description":"","link":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/","name":"New Restaurant! Dinner &amp; Show","slug":"new-restaurant-dinner-show","taxonomy":"category","parent":1,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurantes para despedidas de soltero y soltera - Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Restaurantes para despedidas disponibles en toda Espa\u00f1a. Cena y espect\u00e1culo privado para grupos de despedida de soltera y soltero.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurantes para despedidas de soltero y soltera - Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Restaurantes para despedidas disponibles en toda Espa\u00f1a. Cena y espect\u00e1culo privado para grupos de despedida de soltera y soltero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/\" \/>\n<meta property=\"og:site_name\" content=\"StrippersDeluxe\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurantes para despedidas de soltero y soltera - Espa\u00f1a","description":"Restaurantes para despedidas disponibles en toda Espa\u00f1a. Cena y espect\u00e1culo privado para grupos de despedida de soltera y soltero.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Restaurantes para despedidas de soltero y soltera - Espa\u00f1a","og_description":"Restaurantes para despedidas disponibles en toda Espa\u00f1a. Cena y espect\u00e1culo privado para grupos de despedida de soltera y soltero.","og_url":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/","og_site_name":"StrippersDeluxe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/","url":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/","name":"Restaurantes para despedidas de soltero y soltera - Espa\u00f1a","isPartOf":{"@id":"https:\/\/strippersdeluxe.es\/en\/#website"},"description":"Restaurantes para despedidas disponibles en toda Espa\u00f1a. Cena y espect\u00e1culo privado para grupos de despedida de soltera y soltero.","breadcrumb":{"@id":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/new-restaurant-dinner-show\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/strippersdeluxe.es\/en\/"},{"@type":"ListItem","position":2,"name":"Sin categorizar","item":"https:\/\/strippersdeluxe.es\/en\/category\/sin-categorizar\/"},{"@type":"ListItem","position":3,"name":"New Restaurant! Dinner &amp; Show"}]},{"@type":"WebSite","@id":"https:\/\/strippersdeluxe.es\/en\/#website","url":"https:\/\/strippersdeluxe.es\/en\/","name":"StrippersDeluxe","description":"Organizaci\u00f3n de eventos, despedidas de soltero y soltera, cabar\u00e9 y espect\u00e1culos[:en]Organizaci\u00f3n de eventos, despedidas de soltero y soltera, y espect\u00e1culos","publisher":{"@id":"https:\/\/strippersdeluxe.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strippersdeluxe.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/strippersdeluxe.es\/en\/#organization","name":"StrippersDeluxe","url":"https:\/\/strippersdeluxe.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/strippersdeluxe.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/strippersdeluxe.es\/wp-content\/uploads\/2024\/10\/cropped-cropped-LOGO-1.png","contentUrl":"https:\/\/strippersdeluxe.es\/wp-content\/uploads\/2024\/10\/cropped-cropped-LOGO-1.png","width":1000,"height":516,"caption":"StrippersDeluxe"},"image":{"@id":"https:\/\/strippersdeluxe.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StripDelux\/","https:\/\/x.com\/strippersdeluxe","https:\/\/www.instagram.com\/strippersdeluxe\/","https:\/\/www.youtube.com\/strippersdeluxe"]}]}},"_links":{"self":[{"href":"https:\/\/strippersdeluxe.es\/en\/wp-json\/wp\/v2\/categories\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strippersdeluxe.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/strippersdeluxe.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/strippersdeluxe.es\/en\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/strippersdeluxe.es\/en\/wp-json\/wp\/v2\/posts?categories=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}